{"id":93,"date":"2006-02-23T09:54:11","date_gmt":"2006-02-23T09:54:11","guid":{"rendered":"http:\/\/westpark-gamers.de\/blog\/?p=93"},"modified":"2006-02-23T09:54:11","modified_gmt":"2006-02-23T09:54:11","slug":"22022006-triumvirat-in-caylus","status":"publish","type":"post","link":"https:\/\/www.westpark-gamers.de\/blog\/2006\/02\/23\/22022006-triumvirat-in-caylus\/","title":{"rendered":"22.02.2006: Triumvirat in Caylus"},"content":{"rendered":"<p>Aaron mu\u00dfte in Bangalore die Siemens-Aktien aus dem Keller holen, Peter hatte schon am Montag bei HiG sein Pulver verschossen (er ist schon lange kein Immer-K\u00f6nner mehr!), Loredana auch, Hans ist wieder unter die t\u00e4glichen Malocher gegangen und Andrea hatte eine &#8220;Veranstaltung&#8221; vorgeschoben, was immer man darunter verstehen mag. So fingen drei WPG-Aufrechte mit einer alt-r\u00f6mischen Spezialit\u00e4t an, um nach Arpads Auftreten, der erst noch eine Trainingseinheit beim Fu\u00dfballclub Siemens Nord (als Mittelst\u00fcrmer, nicht als Kassenwart!) absolvieren mu\u00dfte, zu einer neu-franz\u00f6sischen Spezialit\u00e4t \u00fcberzugehen.<br \/><strong>1) Das Ende des Triumvirats<\/strong><br \/>Ein echtes Wargame mit abfedernden Effekten f\u00fcr die jeweils Unterlegenen einer Schlacht: Wer eine Provinz verliert, bekommt zum Ausgleich eine zus\u00e4tzliche Armee! Im der Geographie des Mittelmeerraumes nehmen sich die drei Duces Caesar, Pompejus und No-Oaner gegenseitig die Provinzen ab, um ihre milit\u00e4rischen oder pekuni\u00e4ren Machtmittel auszubauen und damit eine der vielen m\u00f6glichen Siegbedingungen zu erf\u00fcllen.<br \/>In jeder Schlacht verlieren Sieger und Besiegte unabh\u00e4ngig von eingesetztem Geist und Masse immer gleichviel Einheiten, so da\u00df sich taktisches Genie nicht einmal f\u00fcr den gr\u00f6\u00dften Feldherrn aller Zeiten auszahlen w\u00fcrde. Am besten scheint immer noch die Rolle des lachenden Dritten zu sein: Jeder gleichm\u00e4\u00dfige Verlust unter Combatanten mu\u00df zweifellos ein Gewinn f\u00fcr Nicht-Combatanten sein. Doch soweit hatte sich das bei uns noch nicht herumgesprochen. Die verschiedenen Kriegsparteien sind ja auch verf\u00fchrerisch dicht nebeneinander angesiedelt und das Draufschlagen macht einfach Spa\u00df. Jedenfalls verlustifizierten wir uns vom ersten Zug an in Aggressionen.<br \/>G\u00fcnther fand dazwischen sogar noch eine strategische Linie und konnte mittels seiner politischen und milit\u00e4rischen Kompetenzen als erster die Ziellinie \u00fcberschreiten.<br \/>Ein vielseitiges, lustiges Kampfspiel mit einem hervorragenden Material und ausgereiften Regeln. Nach einer kurzen Einschwungphase ist relativ schnell einer der drei Mitspieler irgendwelchen Sieg-Kriterien am nahesten und das ganze Bestreben der jeweiligen Konkurrenten geht darum, ihm gemeinsam noch den Sieg zu nehmen. Gelingt das, steht sofort der n\u00e4chste Spieler kurz vor dem Sieg und sogleich bilden sich neue Fronten. Gelingt das nicht, ist das kurzweilige Spiel zu Ende. L\u00e4nger als eine halbe Stunde braucht es nicht zu dauern. F\u00fcr ein Kriegsspiel ist das doch bemerkenswert kurz, oder?<br \/>Hier gleich noch eine Worterkl\u00e4rung:<br \/>[glowred]&#8221;Triumvirat&#8221; = Triumph des dritten Mannes[\/glowred]<br \/><em>WPG-Wertung: Arpad: 6, G\u00fcnther: 5 , Moritz: 7, Walter: 7.<\/em><br \/>Moritz machte eine Podcast; Walter schreibt eine Rezension, wenn Moritz die Spielregeln wieder mitbringt.<br \/><strong>2. &#8220;Caylus&#8221;<\/strong><br \/>Der H\u00e4ufigkeit nach zu schlie\u00dfen, wie oft wir es in den letzten Wochen gespielt haben, mu\u00df es wirklich ein herausragendes Spiel sein. Vor allem, weil der Spielspa\u00df noch von Mal zu Mal gestiegen ist.<br \/>Moritz zeigte Arpad wo es lang geht:<br \/>[glowred]&#8221;Man mu\u00df bereits in der ersten Runde etwas gegen G\u00fcnther tun, weil der sonst von vorneherein gewonnen hat!&#8221;[\/glowred]<br \/>Doch der Hinweis und sein Befolgen half nichts, G\u00fcnther gewann auch so.<br \/>In Gegensatz zu Meinungs\u00e4u\u00dferungen vieler Kritiker im Internet stellte sich diesmal deutlich heraus, da\u00df &#8220;Caylus&#8221; durchaus Fehler verzeiht. G\u00fcnther spielte keineswegs ohne Fehl und Tadel, besonders in den ersten Runden. Doch die Verluste durch Fehlinvestitionen halten sich in engen Grenzen. Dagegen gibt es sehr viele Zug-Optionen, um die sich die Mitspieler streiten, und unweigerlich mu\u00df immer wieder mal der eine oder der andere dabei Federn lassen, so da\u00df sich ein R\u00fcckstand aufholen l\u00e4\u00dft. Nur wer unfehlbar spielt, verzeiht keine Fehler.<br \/><em>Dem bisherigen WPG-Schnitt von 9,1 dr\u00fcckte Arpad mit seinen 8 Punkten auf 9,0 herunter.<\/em><br \/>Podcast und Rezension sind bereits ver\u00f6ffentlicht.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Aaron mu\u00dfte in Bangalore die Siemens-Aktien aus dem Keller holen, Peter hatte schon am Montag bei HiG sein Pulver verschossen (er ist schon lange kein Immer-K\u00f6nner mehr!), Loredana auch, Hans ist wieder unter die t\u00e4glichen Malocher gegangen und Andrea hatte eine &#8220;Veranstaltung&#8221; vorgeschoben, was immer man darunter verstehen mag. So fingen drei WPG-Aufrechte mit einer &hellip; <a href=\"https:\/\/www.westpark-gamers.de\/blog\/2006\/02\/23\/22022006-triumvirat-in-caylus\/\" class=\"more-link\"><span class=\"screen-reader-text\">22.02.2006: Triumvirat in Caylus<\/span> weiterlesen <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-93","post","type-post","status-publish","format-standard","hentry","category-spieleabende"],"views":723,"_links":{"self":[{"href":"https:\/\/www.westpark-gamers.de\/blog\/wp-json\/wp\/v2\/posts\/93","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.westpark-gamers.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.westpark-gamers.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.westpark-gamers.de\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.westpark-gamers.de\/blog\/wp-json\/wp\/v2\/comments?post=93"}],"version-history":[{"count":0,"href":"https:\/\/www.westpark-gamers.de\/blog\/wp-json\/wp\/v2\/posts\/93\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.westpark-gamers.de\/blog\/wp-json\/wp\/v2\/media?parent=93"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.westpark-gamers.de\/blog\/wp-json\/wp\/v2\/categories?post=93"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.westpark-gamers.de\/blog\/wp-json\/wp\/v2\/tags?post=93"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}